{"id":42990,"date":"2022-07-02T17:13:11","date_gmt":"2022-07-02T17:13:11","guid":{"rendered":"https:\/\/cleopatraweb.com\/?post_type=product&#038;p=42990"},"modified":"2024-09-15T06:06:18","modified_gmt":"2024-09-15T06:06:18","slug":"oneplus-nord-ce-2-lite-5g-2","status":"publish","type":"product","link":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/","title":{"rendered":"OnePlus Nord CE 2 lite 5G &#8211; 128GB\/8GB"},"content":{"rendered":"<p>\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0645\u0645\u064a\u0632\u0627\u062a \u0648\u0639\u064a\u0648\u0628 OnePlus Nord CE 2 lite 5G &#8211; 128GB\/8GB \u0645\u0646 \u0634\u0631\u0643\u0629 OnePlus \u0645\u0646 \u062e\u0644\u0627\u0644 \u0645\u062a\u062c\u0631 \u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646\u060c \u0643\u0645\u0627 \u064a\u0645\u0643\u0646\u0643 \u0645\u0639\u0631\u0641\u0629 \u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0645\u064a\u0632\u0627\u062a \u0648\u0623\u062f\u0627\u0621 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G &#8211; 128GB\/8GB \u0627\u0644\u0630\u064a \u062a\u0642\u062f\u0645\u0647 \u0634\u0631\u0643\u0629 OnePlus \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0623\u0646\u0647 \u064a\u0645\u0643\u0646\u0643 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0645\u0639\u0631\u0641\u0629 \u0623\u062d\u062f\u062b \u0633\u0639\u0631 \u0644\u0640 OnePlus Nord CE 2 lite 5G &#8211; 128GB\/8GB \u0641\u064a 2024 \u0648\u064a\u0645\u0643\u0646\u0643 \u0637\u0644\u0628\u0647 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0637\u0631\u0642 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0645\u062a\u0627\u062d\u0629 \u0623\u0645\u0627\u0645\u0643\u060c \u0648\u0644\u062f\u064a\u0646\u0627 \u0641\u0631\u064a\u0642 \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0627\u0621 \u0627\u0644\u0630\u064a \u064a\u0633\u062a\u0637\u064a\u0639 \u0625\u0631\u0634\u0627\u062f\u0643 \u0641\u064a \u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u0634\u0631\u0627\u0621 \u0633\u0648\u0627\u0621 \u0643\u0627\u0646 \u0627\u0644\u0645\u0646\u062a\u062c \u0627\u0644\u0630\u064a \u062a\u0631\u063a\u0628 \u0628\u0647 OnePlus Nord CE 2 lite 5G &#8211; 128GB\/8GB \u0623\u0648 \u063a\u064a\u0631\u0647 \u0645\u0646 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0631\u064a\u062f\u0647\u0627 \u0641\u064a \u0623\u064a \u0645\u0646\u0637\u0642\u0629 \u0641\u064a \u0633\u0644\u0637\u0646\u0629 \u0639\u0645\u0627\u0646\u060c \u0648\u0647\u0646\u0627 \u0633\u0639\u0631 \u0627\u0644\u0645\u0646\u062a\u062c 96 \u0641\u064a 2024 \u062d\u0627\u0644\u064a\u0627 \u0648\u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u0622\u0646 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0648\u0627\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631 \u0639\u0646 \u0623\u064a \u0645\u0646\u062a\u062c\u0627\u062a \u062a\u0631\u063a\u0628 \u0628\u0647\u0627<\/p>\n","protected":false},"excerpt":{"rendered":"<table dir=\"ltr\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Brand&quot;}\">Brand<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Samsung&quot;}\"><em>OnePlus\u00a0<\/em><\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;RAM&quot;}\">RAM<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;4 GB&quot;}\">8 GB<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Storage&quot;}\">Storage<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;64 GB&quot;}\">128 GB<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Camera Megapixels&quot;}\">Camera Megapixels\u00a0\u00a0<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;48MP&quot;}\">64+2+2 Selfie 16MP<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Battery Capacity&quot;}\">Battery Capacity<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Above 4500 mAh&quot;}\">5000 mAh<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Display&quot;}\">Display<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;6.4 Inch&quot;}\">6.59 Inch<\/td>\n<\/tr>\n<tr>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;OS&quot;}\">Processor<\/td>\n<td data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Android&quot;}\">\n<p>Snapdragon 695 5G\u00a0<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":42992,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"pwb-brand":[649],"product_brand":[648],"product_cat":[774,2572],"product_tag":[],"class_list":{"0":"post-42990","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-oneplus-2","7":"product_brand-oneplus","8":"product_cat-smart-phones-2","9":"product_cat-oneplus_mobile_phones-2","10":"pa_color-blue-ar","11":"pa_color-gray-ar","12":"pa_is-featured-0-6","13":"pa_is-featured-1-1-5","14":"pa_is-used-item-0-9","15":"pa_product-image-size-0-7","16":"pa_product-page-type-default-ar","17":"pa_sale-0-ar","19":"first","20":"outofstock","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0634\u062a\u0631\u064a \u0627\u0644\u0622\u0646 \u0628\u0623\u0641\u0636\u0644 \u0633\u0639\u0631 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a \u0639\u0645\u0627\u0646 | \u0643\u0645\u0627 \u064a\u0645\u0643\u0646\u0643 \u0627\u0633\u062a\u0643\u0634\u0627\u0641 \u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB<\/title>\n<meta name=\"description\" content=\"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0633\u062a\u0643\u0634\u0641 \u0645\u0632\u0627\u064a\u0627 \u0648\u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0645\u0646 \u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646 | \u0648\u0625\u0644\u064a\u0643 \u0623\u062d\u062f\u062b \u0633\u0639\u0631 \u0644\u0640 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a 2023 - 2024\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0634\u062a\u0631\u064a \u0627\u0644\u0622\u0646 \u0628\u0623\u0641\u0636\u0644 \u0633\u0639\u0631 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a \u0639\u0645\u0627\u0646 | \u0643\u0645\u0627 \u064a\u0645\u0643\u0646\u0643 \u0627\u0633\u062a\u0643\u0634\u0627\u0641 \u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB\" \/>\n<meta property=\"og:description\" content=\"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0633\u062a\u0643\u0634\u0641 \u0645\u0632\u0627\u064a\u0627 \u0648\u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0645\u0646 \u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646 | \u0648\u0625\u0644\u064a\u0643 \u0623\u062d\u062f\u062b \u0633\u0639\u0631 \u0644\u0640 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a 2023 - 2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646 \u0627\u0644\u062a\u0633\u0648\u0642 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0639\u0645\u0627\u0646\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cleopatrawebstore\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-15T06:06:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cleopatraweb.com\/wp-content\/uploads\/2022\/07\/products-oneplus-nord-ce-2-lite-5g_1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Cleopatra_Web\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/product\\\/oneplus-nord-ce-2-lite-5g-2\\\/\",\"url\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/product\\\/oneplus-nord-ce-2-lite-5g-2\\\/\",\"name\":\"OnePlus Nord CE 2 lite 5G - 128GB\\\/8GB | \u0627\u0634\u062a\u0631\u064a \u0627\u0644\u0622\u0646 \u0628\u0623\u0641\u0636\u0644 \u0633\u0639\u0631 OnePlus Nord CE 2 lite 5G - 128GB\\\/8GB \u0641\u064a \u0639\u0645\u0627\u0646 | \u0643\u0645\u0627 \u064a\u0645\u0643\u0646\u0643 \u0627\u0633\u062a\u0643\u0634\u0627\u0641 \u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\\\/8GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/product\\\/oneplus-nord-ce-2-lite-5g-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/product\\\/oneplus-nord-ce-2-lite-5g-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cleopatraweb.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/products-oneplus-nord-ce-2-lite-5g_1-1.jpg\",\"datePublished\":\"2022-07-02T17:13:11+00:00\",\"dateModified\":\"2024-09-15T06:06:18+00:00\",\"description\":\"OnePlus Nord CE 2 lite 5G - 128GB\\\/8GB | \u0627\u0633\u062a\u0643\u0634\u0641 \u0645\u0632\u0627\u064a\u0627 \u0648\u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\\\/8GB \u0645\u0646 \u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646 | \u0648\u0625\u0644\u064a\u0643 \u0623\u062d\u062f\u062b \u0633\u0639\u0631 \u0644\u0640 OnePlus Nord CE 2 lite 5G - 128GB\\\/8GB \u0641\u064a 2023 - 2024\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/product\\\/oneplus-nord-ce-2-lite-5g-2\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/product\\\/oneplus-nord-ce-2-lite-5g-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/product\\\/oneplus-nord-ce-2-lite-5g-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cleopatraweb.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/products-oneplus-nord-ce-2-lite-5g_1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cleopatraweb.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/products-oneplus-nord-ce-2-lite-5g_1-1.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/product\\\/oneplus-nord-ce-2-lite-5g-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9-%d8%b3%d8%a8%d8%aa%d9%85%d8%a8%d8%b1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0633\u0648\u0642\",\"item\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/%d8%a7%d9%84%d8%b3%d9%88%d9%82\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"OnePlus Nord CE 2 lite 5G &#8211; 128GB\\\/8GB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/\",\"name\":\"Cleopatra Best Online Shopping Oman\",\"description\":\"Best Online Shopping in Oman\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cleopatraweb.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0634\u062a\u0631\u064a \u0627\u0644\u0622\u0646 \u0628\u0623\u0641\u0636\u0644 \u0633\u0639\u0631 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a \u0639\u0645\u0627\u0646 | \u0643\u0645\u0627 \u064a\u0645\u0643\u0646\u0643 \u0627\u0633\u062a\u0643\u0634\u0627\u0641 \u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB","description":"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0633\u062a\u0643\u0634\u0641 \u0645\u0632\u0627\u064a\u0627 \u0648\u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0645\u0646 \u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646 | \u0648\u0625\u0644\u064a\u0643 \u0623\u062d\u062f\u062b \u0633\u0639\u0631 \u0644\u0640 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a 2023 - 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/","og_locale":"ar_AR","og_type":"article","og_title":"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0634\u062a\u0631\u064a \u0627\u0644\u0622\u0646 \u0628\u0623\u0641\u0636\u0644 \u0633\u0639\u0631 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a \u0639\u0645\u0627\u0646 | \u0643\u0645\u0627 \u064a\u0645\u0643\u0646\u0643 \u0627\u0633\u062a\u0643\u0634\u0627\u0641 \u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB","og_description":"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0633\u062a\u0643\u0634\u0641 \u0645\u0632\u0627\u064a\u0627 \u0648\u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0645\u0646 \u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646 | \u0648\u0625\u0644\u064a\u0643 \u0623\u062d\u062f\u062b \u0633\u0639\u0631 \u0644\u0640 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a 2023 - 2024","og_url":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/","og_site_name":"\u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646 \u0627\u0644\u062a\u0633\u0648\u0642 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u0639\u0645\u0627\u0646","article_publisher":"https:\/\/www.facebook.com\/cleopatrawebstore","article_modified_time":"2024-09-15T06:06:18+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/cleopatraweb.com\/wp-content\/uploads\/2022\/07\/products-oneplus-nord-ce-2-lite-5g_1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Cleopatra_Web","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/","url":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/","name":"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0634\u062a\u0631\u064a \u0627\u0644\u0622\u0646 \u0628\u0623\u0641\u0636\u0644 \u0633\u0639\u0631 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a \u0639\u0645\u0627\u0646 | \u0643\u0645\u0627 \u064a\u0645\u0643\u0646\u0643 \u0627\u0633\u062a\u0643\u0634\u0627\u0641 \u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB","isPartOf":{"@id":"https:\/\/cleopatraweb.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/#primaryimage"},"image":{"@id":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/#primaryimage"},"thumbnailUrl":"https:\/\/cleopatraweb.com\/wp-content\/uploads\/2022\/07\/products-oneplus-nord-ce-2-lite-5g_1-1.jpg","datePublished":"2022-07-02T17:13:11+00:00","dateModified":"2024-09-15T06:06:18+00:00","description":"OnePlus Nord CE 2 lite 5G - 128GB\/8GB | \u0627\u0633\u062a\u0643\u0634\u0641 \u0645\u0632\u0627\u064a\u0627 \u0648\u062e\u0635\u0627\u0626\u0635 \u0648\u0645\u0648\u0627\u0635\u0641\u0627\u062a OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0645\u0646 \u0643\u0644\u064a\u0648\u0628\u0627\u062a\u0631\u0627 \u0639\u0645\u0627\u0646 | \u0648\u0625\u0644\u064a\u0643 \u0623\u062d\u062f\u062b \u0633\u0639\u0631 \u0644\u0640 OnePlus Nord CE 2 lite 5G - 128GB\/8GB \u0641\u064a 2023 - 2024","breadcrumb":{"@id":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/#primaryimage","url":"https:\/\/cleopatraweb.com\/wp-content\/uploads\/2022\/07\/products-oneplus-nord-ce-2-lite-5g_1-1.jpg","contentUrl":"https:\/\/cleopatraweb.com\/wp-content\/uploads\/2022\/07\/products-oneplus-nord-ce-2-lite-5g_1-1.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/cleopatraweb.com\/ar\/product\/oneplus-nord-ce-2-lite-5g-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/cleopatraweb.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9-%d8%b3%d8%a8%d8%aa%d9%85%d8%a8%d8%b1\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0633\u0648\u0642","item":"https:\/\/cleopatraweb.com\/ar\/%d8%a7%d9%84%d8%b3%d9%88%d9%82\/"},{"@type":"ListItem","position":3,"name":"OnePlus Nord CE 2 lite 5G &#8211; 128GB\/8GB"}]},{"@type":"WebSite","@id":"https:\/\/cleopatraweb.com\/ar\/#website","url":"https:\/\/cleopatraweb.com\/ar\/","name":"Cleopatra Best Online Shopping Oman","description":"Best Online Shopping in Oman","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cleopatraweb.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"brands":[{"id":649,"name":"OnePlus","slug":"oneplus-2"}],"_links":{"self":[{"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/product\/42990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/comments?post=42990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/media\/42992"}],"wp:attachment":[{"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/media?parent=42990"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/pwb-brand?post=42990"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/product_brand?post=42990"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/product_cat?post=42990"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cleopatraweb.com\/ar\/wp-json\/wp\/v2\/product_tag?post=42990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}